{"id":1930,"date":"2016-06-18T11:10:16","date_gmt":"2016-06-18T09:10:16","guid":{"rendered":"http:\/\/www.rossiilluminazione.it\/product\/edison-pendant-lamp\/"},"modified":"2020-09-05T12:44:12","modified_gmt":"2020-09-05T10:44:12","slug":"edison-pendant-lamp","status":"publish","type":"product","link":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/","title":{"rendered":"Edison pendant lamp"},"content":{"rendered":"<p>Edison pendant lamp. The US Life magazine, in a special double issue, placed Edison first among the &#8220;100 most important people in the last 1000 years&#8221;, highlighting that his incandescent lamp &#8220;illuminates the world.&#8221; Although Heinrich G\u00f6bel had preceded, with less success, with its own version of the incandescent lamp, Edison was the one who made possible the modern era and spreading commercializing his invention. We present it in its LED version, as original suspension lamp.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LED lamp in suspension, with exposed bulb.<\/p>\n","protected":false},"featured_media":1664,"template":"","meta":[],"product_cat":[65],"product_tag":[],"class_list":{"0":"post-1930","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ceiling-lamps","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Edison pendant lamp di 2026 - Rossi Illuminazione<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edison pendant lamp di 2026 - Rossi Illuminazione\" \/>\n<meta property=\"og:description\" content=\"LED lamp in suspension, with exposed bulb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/\" \/>\n<meta property=\"og:site_name\" content=\"Rossi Illuminazione\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-05T10:44:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2016\/06\/edison_hanging_lamp-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/\",\"url\":\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/\",\"name\":\"Edison pendant lamp di 2026 - Rossi Illuminazione\",\"isPartOf\":{\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2016\/06\/edison_hanging_lamp-scaled.jpg\",\"datePublished\":\"2016-06-18T09:10:16+00:00\",\"dateModified\":\"2020-09-05T10:44:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/#primaryimage\",\"url\":\"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2016\/06\/edison_hanging_lamp-scaled.jpg\",\"contentUrl\":\"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2016\/06\/edison_hanging_lamp-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.rossiilluminazione.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue\",\"item\":\"https:\/\/www.rossiilluminazione.it\/en\/catalogue\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Products\",\"item\":\"https:\/\/www.rossiilluminazione.it\/en\/products-by-categories\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ceiling lamps\",\"item\":\"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Edison pendant lamp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/#website\",\"url\":\"https:\/\/www.rossiilluminazione.it\/en\/\",\"name\":\"Rossi Illuminazione\",\"description\":\"Restauro e realizzazione lampade su misura\",\"publisher\":{\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rossiilluminazione.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/#organization\",\"name\":\"Rossi Illuminazione\",\"url\":\"https:\/\/www.rossiilluminazione.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2019\/05\/logo-dark.png\",\"contentUrl\":\"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2019\/05\/logo-dark.png\",\"width\":114,\"height\":81,\"caption\":\"Rossi Illuminazione\"},\"image\":{\"@id\":\"https:\/\/www.rossiilluminazione.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edison pendant lamp di 2026 - Rossi Illuminazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/","og_locale":"en_US","og_type":"article","og_title":"Edison pendant lamp di 2026 - Rossi Illuminazione","og_description":"LED lamp in suspension, with exposed bulb.","og_url":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/","og_site_name":"Rossi Illuminazione","article_modified_time":"2020-09-05T10:44:12+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2016\/06\/edison_hanging_lamp-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/","url":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/","name":"Edison pendant lamp di 2026 - Rossi Illuminazione","isPartOf":{"@id":"https:\/\/www.rossiilluminazione.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/#primaryimage"},"image":{"@id":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2016\/06\/edison_hanging_lamp-scaled.jpg","datePublished":"2016-06-18T09:10:16+00:00","dateModified":"2020-09-05T10:44:12+00:00","breadcrumb":{"@id":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/#primaryimage","url":"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2016\/06\/edison_hanging_lamp-scaled.jpg","contentUrl":"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2016\/06\/edison_hanging_lamp-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/edison-pendant-lamp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rossiilluminazione.it\/en\/"},{"@type":"ListItem","position":2,"name":"Catalogue","item":"https:\/\/www.rossiilluminazione.it\/en\/catalogue\/"},{"@type":"ListItem","position":3,"name":"Products","item":"https:\/\/www.rossiilluminazione.it\/en\/products-by-categories\/"},{"@type":"ListItem","position":4,"name":"Ceiling lamps","item":"https:\/\/www.rossiilluminazione.it\/en\/ceiling-lamps\/"},{"@type":"ListItem","position":5,"name":"Edison pendant lamp"}]},{"@type":"WebSite","@id":"https:\/\/www.rossiilluminazione.it\/en\/#website","url":"https:\/\/www.rossiilluminazione.it\/en\/","name":"Rossi Illuminazione","description":"Restauro e realizzazione lampade su misura","publisher":{"@id":"https:\/\/www.rossiilluminazione.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rossiilluminazione.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rossiilluminazione.it\/en\/#organization","name":"Rossi Illuminazione","url":"https:\/\/www.rossiilluminazione.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rossiilluminazione.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2019\/05\/logo-dark.png","contentUrl":"https:\/\/www.rossiilluminazione.it\/wp-content\/uploads\/2019\/05\/logo-dark.png","width":114,"height":81,"caption":"Rossi Illuminazione"},"image":{"@id":"https:\/\/www.rossiilluminazione.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.rossiilluminazione.it\/en\/wp-json\/wp\/v2\/product\/1930"}],"collection":[{"href":"https:\/\/www.rossiilluminazione.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.rossiilluminazione.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rossiilluminazione.it\/en\/wp-json\/wp\/v2\/media\/1664"}],"wp:attachment":[{"href":"https:\/\/www.rossiilluminazione.it\/en\/wp-json\/wp\/v2\/media?parent=1930"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.rossiilluminazione.it\/en\/wp-json\/wp\/v2\/product_cat?post=1930"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.rossiilluminazione.it\/en\/wp-json\/wp\/v2\/product_tag?post=1930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}